{"id":23284,"date":"2022-02-18T04:34:35","date_gmt":"2022-02-18T04:34:35","guid":{"rendered":"https:\/\/rstheme.com\/products\/wordpress\/solvency\/?page_id=23284"},"modified":"2026-04-09T12:18:56","modified_gmt":"2026-04-09T12:18:56","slug":"ivoire-consulting-services","status":"publish","type":"page","link":"https:\/\/ivoireconsultingservices.com\/","title":{"rendered":"Onepage 1"},"content":{"rendered":"\t\t<div data-elementor-type=\"wp-page\" data-elementor-id=\"23284\" class=\"elementor elementor-23284\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-76d199b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"76d199b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-8ceafe0\" data-id=\"8ceafe0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab403d9 elementor-widget elementor-widget-slider_revolution\" data-id=\"ab403d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"slider_revolution.default\">\n\t\t\t\t\t\n\t\t<div class=\"wp-block-themepunch-revslider\">\n\t\t\t\t<p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t\t<sr7-module data-alias=\"home\" data-id=\"1\" id=\"SR7_1_1\" class=\"rs-ov-hidden\" data-version=\"6.7.41\">\n\t\t\t\t\t<sr7-adjuster><\/sr7-adjuster>\n\t\t\t\t\t<sr7-content>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_1_1-7\" data-key=\"7\">\n\t\t\t\t\t\t\t<sr7-bg id=\"SR7_1_1-7-3\" class=\"sr7-layer\"><noscript><img decoding=\"async\" src=\"https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/03\/HK.png\" alt=\"\" title=\"HK\"><\/noscript><\/sr7-bg>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-7-1\" class=\"sr7-layer\">Partenaire <br \/>\nde solutions <br \/>\nint\u00e9gr\u00e9es<\/sr7-txt>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-7-2\" class=\"sr7-layer\">Depuis 10 ann\u00e9es<\/sr7-txt>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_1_1-11\" data-key=\"11\">\n\t\t\t\t\t\t\t<sr7-bg id=\"SR7_1_1-11-4\" class=\"sr7-layer\"><noscript><img decoding=\"async\" src=\"https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/03\/Banner-HK-P.jpeg\" alt=\"\" title=\"Banner HK P\"><\/noscript><\/sr7-bg>\n\t\t\t\t\t\t\t<sr7-txt id=\"SR7_1_1-11-1\" class=\"sr7-layer\">Votre <br \/>\nPatrimoine<br \/>\n<br \/>\nNotre <br \/>\nPriorit\u00e9<\/sr7-txt>\n\t\t\t\t\t\t\t<a id=\"SR7_1_1-11-3\" class=\"sr7-layer\" href=\"https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/03\/HK-Property-1403.jpeg\" target=\"_self\">T\u00e9l\u00e9charger notre flyer<\/a>\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_1_1-5\" data-key=\"5\">\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t<\/sr7-content>\n\t\t\t\t\t<image_lists style=\"display:none\">\n\t\t\t\t\t\t<img data-src=\"\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/02\/admin-ajax0.png\" data-libid=\"26388\" data-lib=\"medialibrary\" title=\"admin-ajax0\" width=\"0\" height=\"0\" data-dbsrc=\"Ly9pdm9pcmVjb25zdWx0aW5nc2VydmljZXMuY29tL3dwLWNvbnRlbnQvdXBsb2Fkcy8yMDI2LzAyL2FkbWluLWFqYXgwLnBuZw==\"\/>\n\t\t\t\t\t\t<img data-src=\"\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/03\/HK.png\" data-libid=\"26518\" data-lib=\"medialibrary\" title=\"HK\" width=\"0\" height=\"0\" data-dbsrc=\"Ly9pdm9pcmVjb25zdWx0aW5nc2VydmljZXMuY29tL3dwLWNvbnRlbnQvdXBsb2Fkcy8yMDI2LzAzL0hLLnBuZw==\"\/>\n\t\t\t\t\t\t<img data-src=\"\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/03\/Banner-HK-P.jpeg\" data-libid=\"26720\" data-lib=\"medialibrary\" title=\"Banner HK P\" width=\"0\" height=\"0\" data-dbsrc=\"Ly9pdm9pcmVjb25zdWx0aW5nc2VydmljZXMuY29tL3dwLWNvbnRlbnQvdXBsb2Fkcy8yMDI2LzAzL0Jhbm5lci1ISy1QLmpwZWc=\"\/>\n\t\t\t\t\t<\/image_lists>\n\t\t\t\t<\/sr7-module>\n\t\t\t\t<script>\n\t\t\t\t\tSR7.PMH ??={}; SR7.PMH[\"SR7_1_1\"] = {cn:100,state:false,fn: function() { if (_tpt!==undefined && _tpt.prepareModuleHeight !== undefined) {  _tpt.prepareModuleHeight({id:\"SR7_1_1\",el:[800,800,768,650,550],type:'standard',shdw:'0',gh:[800,800,768,650,550],gw:[1350,1350,1024,778,480],vpt:['-100px&#039;,&#039;-100px&#039;,&#039;-100px&#039;,&#039;-100px&#039;,&#039;-100px'],size:{fullWidth:true, fullHeight:false},mh:'0',onh:0,onw:0,bg:{color:'{\"orig\":\"transparent\",\"type\":\"solid\",\"string\":\"transparent\"}'}});   SR7.PMH[\"SR7_1_1\"].state=true;} else if(SR7.PMH[\"SR7_1_1\"].cn-->0)\tsetTimeout( SR7.PMH[\"SR7_1_1\"].fn,19);}};SR7.PMH[\"SR7_1_1\" ].fn();\n\t\t\t\t<\/script>\n<\/div>\n\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-f5359b1 elementor-section-stretched elementor-section-full_width elementor-section-height-default elementor-section-height-default\" data-id=\"f5359b1\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e9c02b9\" data-id=\"e9c02b9\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-d92a060 elementor-section-stretched elementor-section-content-middle elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"d92a060\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-2b367b4\" data-id=\"2b367b4\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-e7e06f2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e7e06f2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-80bb44d\" data-id=\"80bb44d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-351102c elementor-widget__width-initial elementor-widget elementor-widget-rs-image-hover\" data-id=\"351102c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-image-hover.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t<div class=\"image titlt\" data-tilt data-tilt-max=\"3\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"262\" height=\"300\" src=\"https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/02\/trp0-262x300.png\" class=\"attachment-medium size-medium wp-image-26394\" alt=\"\" srcset=\"https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/02\/trp0-262x300.png 262w, https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/02\/trp0.png 612w\" sizes=\"(max-width: 262px) 100vw, 262px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-be2cce0\" data-id=\"be2cce0\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-3063f9a elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"3063f9a\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-inner-column elementor-element elementor-element-f736f73\" data-id=\"f736f73\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-74ed86a elementor-widget__width-initial elementor-widget elementor-widget-rs-heading\" data-id=\"74ed86a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"prelements-heading default animate- \">\n\n\n\n        \t<div class=\"title-inner\">        \t\t      \t\t\n\t            <span class=\"sub-text \">A propos DE NOUS<\/span><h2 class=\"title\"><span class=\"watermark\"><\/span>Plus de 10 ans d'expertise<\/h2>\t\t\t\t\n\t\t\t\t\t        <\/div>\n\t                    \t<div class=\"description\">\n            \t\t            \t\t<p><span style=\"color: #000080\"><strong>Notre Histoire : <\/strong><\/span><strong><span style=\"color: #000000\">+10 ans d'Engagement et d'Excellence<\/span><\/strong><\/p><p><span style=\"color: #000000\">Fond\u00e9e sur des valeurs de responsabilit\u00e9 et de professionnalisme, Ivoire Consulting Services (ICS) est une soci\u00e9t\u00e9 ivoirienne \u00e9tablie \u00e0 Abidjan depuis plus d'une d\u00e9cennie. Notre succ\u00e8s s'est b\u00e2ti dans les secteurs les plus exigeants comme le P\u00e9trole et le Gaz, o\u00f9 nous avons appris \u00e0 ex\u00e9cuter chaque mission avec une pr\u00e9cision absolue, le bon \u00e9quipement et un jugement s\u00fbr.<\/span><\/p><p><span style=\"color: #000080\"><strong>Notre Vision<\/strong><\/span><\/p><p><strong><span style=\"color: #000000\">Un Hub de Solutions Pluridisciplinaires<\/span><\/strong><br \/><span style=\"color: #000000\">Si notre expertise est n\u00e9e dans l'industrie p\u00e9troli\u00e8re, notre ambition est de mettre cette rigueur au service de tous vos besoins strat\u00e9giques. ICS est votre partenaire unique, capable de d\u00e9ployer des solutions transversales de la logistique critique \u00e0 la gestion de patrimoine avec une promesse centrale : l'Excellence Op\u00e9rationnelle.<\/span><\/p><p><strong><span style=\"color: #000000\">Nos Piliers de Confiance (H\u00e9ritage QHSE)<\/span><\/strong><br \/><span style=\"color: #000000\">Nous appliquons l'exigence de nos d\u00e9buts \u00e0 l'ensemble de notre \u00e9cosyst\u00e8me de services :<\/span><\/p><ul><li><span style=\"color: #000000\"><strong>R\u00e9sultats &amp; S\u00e9curit\u00e9 :<\/strong> Atteindre vos objectifs en agissant avec rapidit\u00e9, excellence et une conformit\u00e9 stricte aux normes QHSE.<\/span><\/li><li><span style=\"color: #000000\"><strong>Expertise Transversale<\/strong> : Un personnel qualifi\u00e9 capable d'intervenir sur des probl\u00e9matiques vari\u00e9es (administratives, techniques, r\u00e9sidentielles) avec un standard de qualit\u00e9 constant.<\/span><\/li><li><span style=\"color: #000000\"><strong>Synergie de Services<\/strong> : En regroupant vos besoins chez ICS, vous b\u00e9n\u00e9ficiez d'une coordination fluide et d'un interlocuteur de confiance pour l'ensemble de vos op\u00e9rations.<\/span><\/li><li><span style=\"color: #000000\"><strong>Croissance Productive<\/strong> : Mettre \u00e0 profit notre exp\u00e9rience pour simplifier votre quotidien et s\u00e9curiser vos investissements.<\/span><\/li><\/ul><p><em><strong><span style=\"color: #000000\">\"De l'ing\u00e9nierie p\u00e9troli\u00e8re au hub de services strat\u00e9giques : l'excellence comme unique standard.\"<\/span><\/strong><\/em><\/p>  \n            \t<\/div>\n        \t        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-2ef50cf elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"2ef50cf\" data-element_type=\"section\" data-e-type=\"section\" id=\"rs-services\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-6cf8fba\" data-id=\"6cf8fba\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f301f5c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f301f5c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-9bf332d\" data-id=\"9bf332d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-dc787f8 elementor-widget elementor-widget-rs-heading\" data-id=\"dc787f8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"prelements-heading default animate- \">\n\n\n\n        \t<div class=\"title-inner\">        \t\t      \t\t\n\t            <span class=\"sub-text \">Nos services<\/span><h2 class=\"title\"><span class=\"watermark\"><\/span>Un savoir-faire reconnu <\/h2>\t\t\t\t\n\t\t\t\t\t        <\/div>\n\t                <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8e93740\" data-id=\"8e93740\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<div class=\"elementor-element elementor-element-b35e334 elementor-widget elementor-widget-rs-tab-advanced\" data-id=\"b35e334\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-tab-advanced.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"rstab-main horizontal no_item_menu\"> \n            <ul  class=\"nav nav-nav-tabs basic left\">\n                                    <li class=\"nav-item\"><a class=\"nav-link active\" data-toggle=\"tab\" href=\"#a11054505\">\n                                                        <em>\n                                    <img decoding=\"async\" class=\"nor_img\" src=\"https:\/\/rstheme.com\/products\/wordpress\/solvency\/wp-content\/uploads\/2022\/02\/credit-card.png\" alt=\"icon-image\" \/>                                    <img decoding=\"async\" class=\"hob_img\" src=\"https:\/\/rstheme.com\/products\/wordpress\/solvency\/wp-content\/uploads\/2022\/02\/1credit-card.png\" alt=\"icon-image\"\/>                                <\/em>                                \n                                                    Conformit\u00e9 <\/a>\n                    <\/li>\n\n                                    <li class=\"nav-item\"><a class=\"nav-link \" data-toggle=\"tab\" href=\"#a21054505\">\n                                                        <em>\n                                    <img decoding=\"async\" class=\"nor_img\" src=\"https:\/\/rstheme.com\/products\/wordpress\/solvency\/wp-content\/uploads\/2022\/02\/audit.png\" alt=\"icon-image\" \/>                                    <img decoding=\"async\" class=\"hob_img\" src=\"https:\/\/rstheme.com\/products\/wordpress\/solvency\/wp-content\/uploads\/2022\/02\/1audit.png\" alt=\"icon-image\"\/>                                <\/em>                                \n                                                    Mobilit\u00e9 &amp; Visas<\/a>\n                    <\/li>\n\n                                    <li class=\"nav-item\"><a class=\"nav-link \" data-toggle=\"tab\" href=\"#a31054505\">\n                                                        <em>\n                                    <img decoding=\"async\" class=\"nor_img\" src=\"https:\/\/rstheme.com\/products\/wordpress\/solvency\/wp-content\/uploads\/2022\/02\/resume.png\" alt=\"icon-image\" \/>                                    <img decoding=\"async\" class=\"hob_img\" src=\"https:\/\/rstheme.com\/products\/wordpress\/solvency\/wp-content\/uploads\/2022\/02\/1resume.png\" alt=\"icon-image\"\/>                                <\/em>                                \n                                                    Support Op\u00e9rationnel<\/a>\n                    <\/li>\n\n                                    <li class=\"nav-item\"><a class=\"nav-link \" data-toggle=\"tab\" href=\"#a41054505\">\n                                                        <em>\n                                    <img decoding=\"async\" class=\"nor_img\" src=\"https:\/\/rstheme.com\/products\/wordpress\/solvency\/wp-content\/uploads\/2022\/02\/business.png\" alt=\"icon-image\" \/>                                    <img decoding=\"async\" class=\"hob_img\" src=\"https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2022\/02\/reliability.png\" alt=\"icon-image\"\/>                                <\/em>                                \n                                                    HK Property<\/a>\n                    <\/li>\n\n                                    \n            <\/ul>\n\n            <div class=\"tab-content clearfix\">\n                                       \n                        <div class=\"tab-pane active\" id=\"a11054505\">\n                                                            \n                        <\/div>\n                                       \n                        <div class=\"tab-pane \" id=\"a21054505\">\n                            \t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"99\" class=\"elementor elementor-99\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-ca251d9 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ca251d9\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-266cf08\" data-id=\"266cf08\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-4c0b476 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"4c0b476\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-68f8b56\" data-id=\"68f8b56\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ab61443 elementor-widget elementor-widget-rs-heading\" data-id=\"ab61443\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"prelements-heading default animate- \">\n\n\n\n        \t<div class=\"title-inner\">        \t\t      \t\t\n\t            <span class=\"sub-text \">Mobilit\u00e9 Internationale &amp; Conciergerie VIP<\/span><h2 class=\"title\"><span class=\"watermark\"><\/span>Mobilit\u00e9 &amp; Visas<\/h2>\t\t\t\t\n\t\t\t\t\t        <\/div>\n\t                    \t<div class=\"description\">\n            \t\t            \t\t<p>Une gestion sans couture de vos arriv\u00e9es et de vos s\u00e9jours. Nous assurons vos formalit\u00e9s d'immigration en temps record : Visas express (48h), cartes de r\u00e9sident et autorisations sp\u00e9ciales. D\u00e8s votre descente d'avion, b\u00e9n\u00e9ficiez de notre service \"Meet &amp; Greet\" exclusif (accueil passerelle, priorit\u00e9 immigration) et d'un transfert s\u00e9curis\u00e9 jusqu'\u00e0 votre destination. ICS transforme la logistique complexe en une exp\u00e9rience fluide et prioritaire.<\/p>  \n            \t<\/div>\n        \t        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-05b2c1c\" data-id=\"05b2c1c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-fae07a7 elementor-widget elementor-widget-rs-image-hover\" data-id=\"fae07a7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-image-hover.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t<div class=\"image titlt\" data-tilt data-tilt-max=\"3\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"661\" src=\"https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2022\/02\/Visa-ICS-991x1024.png\" class=\"attachment-large size-large wp-image-26475\" alt=\"\" srcset=\"https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2022\/02\/Visa-ICS-991x1024.png 991w, https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2022\/02\/Visa-ICS-290x300.png 290w, https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2022\/02\/Visa-ICS-768x794.png 768w, https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2022\/02\/Visa-ICS.png 1157w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t                                \n                        <\/div>\n                                       \n                        <div class=\"tab-pane \" id=\"a31054505\">\n                            \t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"101\" class=\"elementor elementor-101\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-534cf6c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"534cf6c\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-485459f\" data-id=\"485459f\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-1429980 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"1429980\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d31569d\" data-id=\"d31569d\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c15c67b elementor-widget elementor-widget-rs-heading\" data-id=\"c15c67b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"prelements-heading default animate- \">\n\n\n\n        \t<div class=\"title-inner\">        \t\t      \t\t\n\t            <span class=\"sub-text \">Support Op\u00e9rationnel &amp; Assistance Business<\/span><h2 class=\"title\"><span class=\"watermark\"><\/span>Support Op\u00e9rationnel<\/h2>\t\t\t\t\n\t\t\t\t\t        <\/div>\n\t                    \t<div class=\"description\">\n            \t\t            \t\t<p>Coordination logistique et optimisation de vos ressources internes. Nous assurons la mise \u00e0 disposition de chauffeurs VIP, la s\u00e9curisation de vos convois et la gestion de vos flux de personnels. ICS va plus loin en proposant des agents d'accueil et d'appui administratif qualifi\u00e9s, experts en organisation et outils digitaux. Que ce soit sur site industriel ou en si\u00e8ge social, nous garantissons une disponibilit\u00e9 24\/7 pour fluidifier vos op\u00e9rations et moderniser votre gestion quotidienne.<\/p>  \n            \t<\/div>\n        \t        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fac229c\" data-id=\"fac229c\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-f49d37d elementor-widget elementor-widget-rs-image-hover\" data-id=\"f49d37d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-image-hover.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t<div class=\"image titlt\" data-tilt data-tilt-max=\"3\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"671\" src=\"https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/02\/a-propos-4-977x1024.png\" class=\"attachment-large size-large wp-image-26445\" alt=\"\" srcset=\"https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/02\/a-propos-4-977x1024.png 977w, https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/02\/a-propos-4-286x300.png 286w, https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/02\/a-propos-4-768x805.png 768w, https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/02\/a-propos-4.png 1166w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t                                \n                        <\/div>\n                                       \n                        <div class=\"tab-pane \" id=\"a41054505\">\n                            \t\t<div data-elementor-type=\"wp-post\" data-elementor-id=\"103\" class=\"elementor elementor-103\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-9ee1434 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9ee1434\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-e2ad687\" data-id=\"e2ad687\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-5ac9eae elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"5ac9eae\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-35726c8\" data-id=\"35726c8\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4adc9e7 elementor-widget elementor-widget-rs-heading\" data-id=\"4adc9e7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"prelements-heading default animate- \">\n\n\n\n        \t<div class=\"title-inner\">        \t\t      \t\t\n\t            <span class=\"sub-text \">Gestion &amp; Vision Patrimoniale<\/span><h2 class=\"title\"><span class=\"watermark\"><\/span>HK Property<\/h2>\t\t\t\t\n\t\t\t\t\t        <\/div>\n\t                    \t<div class=\"description\">\n            \t\t            \t\t<p><strong>Valorisez et s\u00e9curisez vos investissements immobiliers.<\/strong><\/p><p>Nous assurons la gestion locative int\u00e9grale de vos biens pour maximiser votre rentabilit\u00e9 et pr\u00e9server votre patrimoine sur le long terme.<br \/>Pour nos clients en qu\u00eate d'excellence, nous s\u00e9lectionnons les meilleurs h\u00e9bergements haut de gamme \u00e0 Abidjan.\u00a0<\/p><p><em><strong>Avec HK Property, l'immobilier devient simple et s\u00e9curis\u00e9.<\/strong><\/em><\/p>  \n            \t<\/div>\n        \t        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4f16723 elementor-button-warning elementor-align-left elementor-widget elementor-widget-button\" data-id=\"4f16723\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t\t\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/04\/HK-Property-1403.jpeg\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t<span class=\"elementor-button-icon\">\n\t\t\t\t<svg aria-hidden=\"true\" class=\"e-font-icon-svg e-fas-download\" viewBox=\"0 0 512 512\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\"><path d=\"M216 0h80c13.3 0 24 10.7 24 24v168h87.7c17.8 0 26.7 21.5 14.1 34.1L269.7 378.3c-7.5 7.5-19.8 7.5-27.3 0L90.1 226.1c-12.6-12.6-3.7-34.1 14.1-34.1H192V24c0-13.3 10.7-24 24-24zm296 376v112c0 13.3-10.7 24-24 24H24c-13.3 0-24-10.7-24-24V376c0-13.3 10.7-24 24-24h146.7l49 49c20.1 20.1 52.5 20.1 72.6 0l49-49H488c13.3 0 24 10.7 24 24zm-124 88c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20zm64 0c0-11-9-20-20-20s-20 9-20 20 9 20 20 20 20-9 20-20z\"><\/path><\/svg>\t\t\t<\/span>\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">T\u00e9l\u00e9charger notre flyer<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a15d53b\" data-id=\"a15d53b\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8315d57 elementor-widget elementor-widget-rs-image-hover\" data-id=\"8315d57\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-image-hover.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t<div class=\"image titlt\" data-tilt data-tilt-max=\"3\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/rstheme.com\/products\/wordpress\/solvency\/wp-content\/uploads\/2022\/02\/img.png\" title=\"\" alt=\"\" loading=\"lazy\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-31d01e5 elementor-widget elementor-widget-rs-image-hover\" data-id=\"31d01e5\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-image-hover.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-image\">\n\t\t\t<div class=\"image titlt\" data-tilt data-tilt-max=\"3\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"640\" height=\"685\" src=\"https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2022\/02\/HK-Property2-957x1024.png\" class=\"attachment-large size-large wp-image-26795\" alt=\"\" srcset=\"https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2022\/02\/HK-Property2-957x1024.png 957w, https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2022\/02\/HK-Property2-280x300.png 280w, https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2022\/02\/HK-Property2-768x822.png 768w, https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2022\/02\/HK-Property2.png 1104w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>\n\t\t                                \n                        <\/div>\n                                                               \n            <\/div>\n          \n        <\/div>\n   \n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-61b52ca elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"61b52ca\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-eb28e29 elementor-hidden-mobile\" data-id=\"eb28e29\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-61a0615\" data-id=\"61a0615\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-a839c5d elementor-widget elementor-widget-rs-heading\" data-id=\"a839c5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        <div class=\"prelements-heading style4 animate-intro-move-x center\">\n\n\n\n        \t<div class=\"title-inner\">        \t\t      \t\t\n\t            <h2 class=\"title\"><span class=\"watermark\"><\/span>Offre partenaire 2026<\/h2>\t\t\t\t\n\t\t\t\t\t        <\/div>\n\t                    \t<div class=\"description\">\n            \t\t            \t\t<h3><span style=\"color: #ffffff\"><strong><span style=\"color: #ffff00\">-50% sur vos 3 premi\u00e8res sollicitations<\/span><\/strong><\/span><\/h3><h3><span style=\"color: #ffffff\"><strong>Visas, Licences de sources radioactives, Licences de substances explosives ou Cartes de r\u00e9sident<\/strong><\/span><\/h3>  \n            \t<\/div>\n        \t        <\/div>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-5abef89 elementor-widget elementor-widget-rs-button\" data-id=\"5abef89\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"rs-btn style1\">\r\n\t\t\t\t\t\t\t\t<a class=\"rs_button\" href=\"\" >\t\t\t\t\r\n\t\t\t\t\t<span class=\"btn_text\">D\u00e9couvrir l&#039;offre<\/span>\r\n\t\t\t\t\t\t\t\t\t<\/a>\r\n\t\t\t<\/div> \r\n\t\t   \r\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-top-column elementor-element elementor-element-e6d00f7 elementor-hidden-mobile\" data-id=\"e6d00f7\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-38fa96d e-flex e-con-boxed e-con e-parent\" data-id=\"38fa96d\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-38af786 elementor-widget elementor-widget-spacer\" data-id=\"38af786\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"spacer.default\">\n\t\t\t\t\t\t\t<div class=\"elementor-spacer\">\n\t\t\t<div class=\"elementor-spacer-inner\"><\/div>\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-8b6f0d6 e-flex e-con-boxed e-con e-parent\" data-id=\"8b6f0d6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-896af7c elementor-widget elementor-widget-heading\" data-id=\"896af7c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Demande de devis<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e1f7a5d elementor-widget elementor-widget-wpforms\" data-id=\"e1f7a5d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-26585\"><form id=\"wpforms-form-26585\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"26585\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/23284\" data-token=\"0db5adb37bd907db4e3a0b9e3abf7bb5\" data-token-time=\"1784148285\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-26585-field_4-container\" class=\"wpforms-field wpforms-field-text\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-26585-field_4\">Entreprise <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"text\" id=\"wpforms-26585-field_4\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][4]\" aria-errormessage=\"wpforms-26585-field_4-error\" required><\/div>\t\t<div id=\"wpforms-26585-field_5-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"5\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-26585-field_5\" >sollicit\u00e9 E-mail T\u00e9l\u00e9phone<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-26585-field_5\" class=\"wpforms-field-medium\" name=\"wpforms[fields][5]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-26585-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-26585-field_2\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-26585-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-26585-field_2-error\" required><\/div><div id=\"wpforms-26585-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label\">Nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-26585-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" aria-errormessage=\"wpforms-26585-field_1-error\" required><label for=\"wpforms-26585-field_1\" class=\"wpforms-field-sublabel after\">Pr\u00e9nom<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-26585-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" aria-errormessage=\"wpforms-26585-field_1-last-error\" required><label for=\"wpforms-26585-field_1-last\" class=\"wpforms-field-sublabel after\">Nom<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-26585-field_7-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"7\"><label class=\"wpforms-field-label\" for=\"wpforms-26585-field_7\">T\u00e9l\u00e9phone <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-26585-field_7\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][7]\" step=\"any\" aria-errormessage=\"wpforms-26585-field_7-error\" required><\/div><div id=\"wpforms-26585-field_6-container\" class=\"wpforms-field wpforms-field-checkbox wpforms-list-2-columns\" data-field-id=\"6\"><fieldset><legend class=\"wpforms-field-label\">Service sollicit\u00e9 <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><ul id=\"wpforms-26585-field_6\" class=\"wpforms-field-required\"><li class=\"choice-1 depth-1\"><input type=\"checkbox\" id=\"wpforms-26585-field_6_1\" name=\"wpforms[fields][6][]\" value=\"Expertise r\u00e8glementaire\" aria-errormessage=\"wpforms-26585-field_6_1-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-26585-field_6_1\">Expertise r\u00e8glementaire<\/label><\/li><li class=\"choice-2 depth-1\"><input type=\"checkbox\" id=\"wpforms-26585-field_6_2\" name=\"wpforms[fields][6][]\" value=\"Mobilit\u00e9 &amp; Visas\" aria-errormessage=\"wpforms-26585-field_6_2-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-26585-field_6_2\">Mobilit\u00e9 &amp; Visas<\/label><\/li><li class=\"choice-3 depth-1\"><input type=\"checkbox\" id=\"wpforms-26585-field_6_3\" name=\"wpforms[fields][6][]\" value=\"Support op\u00e9rationnel\" aria-errormessage=\"wpforms-26585-field_6_3-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-26585-field_6_3\">Support op\u00e9rationnel<\/label><\/li><li class=\"choice-4 depth-1\"><input type=\"checkbox\" id=\"wpforms-26585-field_6_4\" name=\"wpforms[fields][6][]\" value=\"HK Property\" aria-errormessage=\"wpforms-26585-field_6_4-error\" required ><label class=\"wpforms-field-label-inline\" for=\"wpforms-26585-field_6_4\">HK Property<\/label><\/li><\/ul><\/fieldset><\/div><div id=\"wpforms-26585-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-26585-field_3\">Message<\/label><textarea id=\"wpforms-26585-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-26585-field_3-error\" ><\/textarea><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-26585-field_5-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-26585-field_5-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-26585-field_5-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"26585\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/ivoireconsultingservices.com\/index.php\/wp-json\/wp\/v2\/pages\/23284\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-26585\" class=\"wpforms-submit\" data-alt-text=\"Envoi...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ivoireconsultingservices.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-602d379 elementor-section-stretched elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"602d379\" data-element_type=\"section\" data-e-type=\"section\" data-settings=\"{&quot;stretch_section&quot;:&quot;section-stretched&quot;,&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-39402bd\" data-id=\"39402bd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b08a5c8 elementor-widget elementor-widget-heading\" data-id=\"b08a5c8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">Une confiance accr\u00e9dit\u00e9e par les leaders du secteur<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-85b23a1 elementor-widget elementor-widget-rs-logo\" data-id=\"85b23a1\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"rs-logo.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\n        \n            <div class=\"rsaddon-unique-slider\">\n                <div id=\"rsaddon-slick-slider-25106\" class=\"rs-addon-slider rsl_style1\">                      \n                                                <div class=\"grid-item \">\n                                <div  class=\"rs-grid-figure\">\n                                    <div class=\"logo-img ddddd\">\n                                                                                    <a>\n                                            <img decoding=\"async\" class=\"hovers-logos rs-grid-img \"  src=\"https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/02\/logo-slb.png\" title=\"\" alt=\"\">\n                                                <img decoding=\"async\" class=\"mains-logos rs-grid-img \"  src=\"https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/02\/logo-slb.png\" title=\"\" alt=\"\"><\/a>\n                                                                            <\/div>\n                                                                                                        <\/div>\n                            <\/div>           \n                                                    <div class=\"grid-item \">\n                                <div  class=\"rs-grid-figure\">\n                                    <div class=\"logo-img ddddd\">\n                                                                                    <a>\n                                            <img decoding=\"async\" class=\"hovers-logos rs-grid-img \"  src=\"https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/02\/logo-HALLIBURTON.jpg\" title=\"\" alt=\"\">\n                                                <img decoding=\"async\" class=\"mains-logos rs-grid-img \"  src=\"https:\/\/ivoireconsultingservices.com\/wp-content\/uploads\/2026\/02\/logo-HALLIBURTON.jpg\" title=\"\" alt=\"\"><\/a>\n                                                                            <\/div>\n                                                                                                        <\/div>\n                            <\/div>           \n                                              \n                <\/div>\n                <div class=\"rsaddon-slider-conf wpsisac-hide\" data-conf=\"{&quot;slidesToShow&quot;:&quot;2&quot;,&quot;autoplaySpeed&quot;:3000,&quot;interval&quot;:3000,&quot;slidesToScroll&quot;:2,&quot;slider_autoplay&quot;:&quot;true&quot;,&quot;pauseOnHover&quot;:&quot;true&quot;,&quot;sliderDots&quot;:&quot;true&quot;,&quot;sliderNav&quot;:&quot;true&quot;,&quot;infinite&quot;:&quot;false&quot;,&quot;centerMode&quot;:&quot;false&quot;,&quot;col_lg&quot;:&quot;2&quot;,&quot;col_md&quot;:&quot;2&quot;,&quot;col_sm&quot;:2,&quot;col_xs&quot;:&quot;2&quot;}\"><\/div>\n            <\/div>\n            <script type=\"text\/javascript\"> \n                jQuery(document).ready(function(){\n                    jQuery( '.rs-addon-slider' ).each(function( index ) {        \n                    var slider_id       = jQuery(this).attr('id'); \n                    var slider_conf     = jQuery.parseJSON( jQuery(this).closest('.rsaddon-unique-slider').find('.rsaddon-slider-conf').attr('data-conf'));\n                   \n                    if( typeof(slider_id) != 'undefined' && slider_id != '' ) {\n                    jQuery('#'+slider_id).not('.slick-initialized').slick({\n                    slidesToShow    : parseInt(slider_conf.col_lg),\n                    centerMode      : (slider_conf.centerMode)  == \"true\" ? true : false,\n                    dots            : (slider_conf.sliderDots)  == \"true\" ? true : false,\n                    arrows          : (slider_conf.sliderNav) == \"true\" ? true : false,\n                    autoplay        : (slider_conf.slider_autoplay) == \"true\" ? true : false,\n                    slidesToScroll  : parseInt(slider_conf.slidesToScroll),\n                    centerPadding   : '15px',\n                    autoplaySpeed   : parseInt(slider_conf.autoplaySpeed),\n                    pauseOnHover    : (slider_conf.pauseOnHover) == \"true\" ? true : false,\n                    loop : false,\n\n                    responsive: [{\n                        breakpoint: 1200,\n                        settings: {\n                            slidesToShow: parseInt(slider_conf.col_md),\n                        }\n                    }, \n                    {\n                        breakpoint: 992,\n                        settings: {\n                            slidesToShow: parseInt(slider_conf.col_sm),\n                        }\n                    }, \n                    {\n                        breakpoint: 768,\n                        settings: {\n                            arrows: false,\n                            slidesToShow: parseInt(slider_conf.col_xs),\n                        }\n                    }, ]\n                    });\n                }\n               \n                });\n            });\n            <\/script>\n        \t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-8118f1b e-flex e-con-boxed e-con e-parent\" data-id=\"8118f1b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c7b25d0 elementor-widget elementor-widget-heading\" data-id=\"c7b25d0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Parlons-nous<\/h2>\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1606196 e-flex e-con-boxed e-con e-parent\" data-id=\"1606196\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-975acd6 elementor-widget elementor-widget-wpforms\" data-id=\"975acd6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"wpforms.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"wpforms-container wpforms-container-full wpforms-render-modern\" id=\"wpforms-26567\"><form id=\"wpforms-form-26567\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"26567\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/23284\" data-token=\"fb6873d53ff737b5bd4be09beb25322c\" data-token-time=\"1784148285\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div id=\"wpforms-error-noscript\" style=\"display: none;\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/div><div class=\"wpforms-field-container\"><div id=\"wpforms-26567-field_1-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"1\"><fieldset><legend class=\"wpforms-field-label\">Nom <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/legend><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-26567-field_1\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][1][first]\" aria-errormessage=\"wpforms-26567-field_1-error\" required><label for=\"wpforms-26567-field_1\" class=\"wpforms-field-sublabel after\">Pr\u00e9nom<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-26567-field_1-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][1][last]\" aria-errormessage=\"wpforms-26567-field_1-last-error\" required><label for=\"wpforms-26567-field_1-last\" class=\"wpforms-field-sublabel after\">Nom<\/label><\/div><\/div><\/fieldset><\/div><div id=\"wpforms-26567-field_2-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-26567-field_2\">E-mail <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"email\" id=\"wpforms-26567-field_2\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][2]\" spellcheck=\"false\" aria-errormessage=\"wpforms-26567-field_2-error\" required><\/div><div id=\"wpforms-26567-field_4-container\" class=\"wpforms-field wpforms-field-number\" data-field-id=\"4\"><label class=\"wpforms-field-label\" for=\"wpforms-26567-field_4\">WhatsApp <span class=\"wpforms-required-label\" aria-hidden=\"true\">*<\/span><\/label><input type=\"number\" id=\"wpforms-26567-field_4\" class=\"wpforms-field-small wpforms-field-required\" name=\"wpforms[fields][4]\" step=\"any\" aria-errormessage=\"wpforms-26567-field_4-error\" required><\/div>\t\t<div id=\"wpforms-26567-field_5-container\"\n\t\t\tclass=\"wpforms-field wpforms-field-text\"\n\t\t\tdata-field-type=\"text\"\n\t\t\tdata-field-id=\"5\"\n\t\t\t>\n\t\t\t<label class=\"wpforms-field-label\" for=\"wpforms-26567-field_5\" >message Nom ou<\/label>\n\t\t\t<input type=\"text\" id=\"wpforms-26567-field_5\" class=\"wpforms-field-medium\" name=\"wpforms[fields][5]\" >\n\t\t<\/div>\n\t\t<div id=\"wpforms-26567-field_3-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"3\"><label class=\"wpforms-field-label\" for=\"wpforms-26567-field_3\">Commentaire ou message<\/label><textarea id=\"wpforms-26567-field_3\" class=\"wpforms-field-medium\" name=\"wpforms[fields][3]\" aria-errormessage=\"wpforms-26567-field_3-error\" ><\/textarea><\/div><script>\n\t\t\t\t( function() {\n\t\t\t\t\tconst style = document.createElement( 'style' );\n\t\t\t\t\tstyle.appendChild( document.createTextNode( '#wpforms-26585-field_5-container,#wpforms-26567-field_5-container { position: absolute !important; overflow: hidden !important; display: inline !important; height: 1px !important; width: 1px !important; z-index: -1000 !important; padding: 0 !important; } #wpforms-26585-field_5-container,#wpforms-26567-field_5-container input { visibility: hidden; } #wpforms-conversational-form-page #wpforms-26585-field_5-container,#wpforms-26567-field_5-container label { counter-increment: none; }' ) );\n\t\t\t\t\tdocument.head.appendChild( style );\n\t\t\t\t\tdocument.currentScript?.remove();\n\t\t\t\t} )();\n\t\t\t<\/script><\/div><!-- .wpforms-field-container --><div class=\"wpforms-submit-container\" ><input type=\"hidden\" name=\"wpforms[id]\" value=\"26567\"><input type=\"hidden\" name=\"page_title\" value=\"\"><input type=\"hidden\" name=\"page_url\" value=\"https:\/\/ivoireconsultingservices.com\/index.php\/wp-json\/wp\/v2\/pages\/23284\"><input type=\"hidden\" name=\"url_referer\" value=\"\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-26567\" class=\"wpforms-submit\" data-alt-text=\"Envoi...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/ivoireconsultingservices.com\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><\/form><\/div>  <!-- .wpforms-container -->\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t","protected":false},"excerpt":{"rendered":"<p>A propos DE NOUS Plus de 10 ans d&#8217;expertise Notre Histoire : +10 ans d&#8217;Engagement et d&#8217;Excellence Fond\u00e9e sur des valeurs de responsabilit\u00e9 et de professionnalisme, Ivoire Consulting Services (ICS) est une soci\u00e9t\u00e9 ivoirienne \u00e9tablie \u00e0 Abidjan depuis plus d&#8217;une d\u00e9cennie. Notre succ\u00e8s s&#8217;est b\u00e2ti dans les secteurs les plus exigeants comme le P\u00e9trole et&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-single.php","meta":{"footnotes":""},"class_list":["post-23284","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/ivoireconsultingservices.com\/index.php\/wp-json\/wp\/v2\/pages\/23284","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ivoireconsultingservices.com\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ivoireconsultingservices.com\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ivoireconsultingservices.com\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ivoireconsultingservices.com\/index.php\/wp-json\/wp\/v2\/comments?post=23284"}],"version-history":[{"count":173,"href":"https:\/\/ivoireconsultingservices.com\/index.php\/wp-json\/wp\/v2\/pages\/23284\/revisions"}],"predecessor-version":[{"id":26766,"href":"https:\/\/ivoireconsultingservices.com\/index.php\/wp-json\/wp\/v2\/pages\/23284\/revisions\/26766"}],"wp:attachment":[{"href":"https:\/\/ivoireconsultingservices.com\/index.php\/wp-json\/wp\/v2\/media?parent=23284"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}